{"id":4604,"date":"2025-07-30T16:21:59","date_gmt":"2025-07-30T16:21:59","guid":{"rendered":"https:\/\/imperioelectrodomesticos.uy\/?post_type=product&#038;p=4604"},"modified":"2026-02-04T14:11:40","modified_gmt":"2026-02-04T14:11:40","slug":"monopatin-scooter-electrico-proove-xcity-pro-max-550w","status":"publish","type":"product","link":"https:\/\/imperioelectrodomesticos.uy\/index.php\/producto\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\/","title":{"rendered":"Monopat\u00edn El\u00e9ctrico Proove XCity Pro Max 550W"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<div class=\"nombre_cont\">\n<h1 class=\"nombre\">Scooter El\u00e9ctrico Proove XCity Pro Max 550W<\/h1>\n<p>&nbsp;<\/p>\n<\/div>\n<h2 class=\"copete_ficha\">Capacidad de la bater\u00eda: 15,6 Ah 48 V<br \/>\nMontaje de la bater\u00eda: Extra\u00edble<br \/>\nTipo de bater\u00eda: Litio<br \/>\nPotencia de carga: 2,0 A<br \/>\nSubida en pendientes: hasta 25\u00b0<br \/>\nPeso del dispositivo: 23 kg<br \/>\nReposapi\u00e9s: Aluminio, punta de pl\u00e1stico duro<br \/>\nMaterial del cuadro: Aluminio de aviaci\u00f3n<br \/>\nFrenos delanteros: Disco + Regenerativo<br \/>\nLuz delantera: Linterna LED<br \/>\nTiempo de carga completa: 7 horas<br \/>\nGarant\u00eda: 6 meses<br \/>\nFijaci\u00f3n del manillar: No extra\u00edble<br \/>\nMaterial del manillar: Poliuretano texturizado de dureza media<br \/>\nM\u00e1x. Reserva de marcha: 60 km<br \/>\nCarga m\u00e1xima: hasta 120 kg<br \/>\nVelocidad m\u00e1xima: 40 km\/h<br \/>\nRueda motriz: Impermeable<br \/>\nN\u00famero de modos de velocidad: 3<br \/>\nPotencia nominal: 550 W<br \/>\nFrenos traseros: Disco + Regenerativo<br \/>\nLuz trasera: Linterna LED<br \/>\nEdad recomendada: a partir de 16 a\u00f1os<br \/>\nNeum\u00e1ticos: Goma resistente al desgaste<br \/>\nTipo de neum\u00e1ticos: Sin c\u00e1mara<br \/>\nImpermeable: IP54<br \/>\nDi\u00e1metro de las ruedas: 10&#8243;<\/h2>\n<h4 id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" aria-label=\"Translated text: Caracter\u00edsticas t\u00e9cnicas El modelo X-City Pro Max tiene una potencia m\u00e1xima de 550 W y una velocidad m\u00e1xima de 40 km\/h, lo que le permite moverse eficientemente por la ciudad y alcanzar r\u00e1pidamente la velocidad necesaria. El patinete el\u00e9ctrico est\u00e1 equipado con una bater\u00eda de 15,6 Ah con una corriente de 48 V, que le permite recorrer hasta 60 km, dependiendo de la velocidad del veh\u00edculo. Construcci\u00f3n y dise\u00f1o El modelo X-City Pro Max est\u00e1 fabricado en aluminio aeron\u00e1utico y tiene un dise\u00f1o plegable. Esto facilita su transporte y almacenamiento en casa. Todos los cables pasan por el interior del chasis, para que no molesten durante la conducci\u00f3n. Su distintiva combinaci\u00f3n de colores negro y naranja llama la atenci\u00f3n y se adapta perfectamente al ajetreo de la vida urbana. Seguridad y comodidad El X-City Pro Max cuenta con frenos de disco regenerativos fiables que le ayudan a reducir la velocidad r\u00e1pidamente y a recuperar la energ\u00eda de la bater\u00eda. Sus tres modos de velocidad le permiten personalizar el ritmo para usted o su hijo. Una plataforma con estructura de alivio que mantiene los pies firmemente en su lugar.\" data-ved=\"2ahUKEwjL8LS3xoeOAxXOr5UCHfIpKf8Q3ewLegQIDRAV\"><span class=\"Y2IQFc\" lang=\"es\">El modelo X-City Pro Max tiene una potencia m\u00e1xima de 550 W<br \/>\ny una velocidad m\u00e1xima de 40 km\/h, lo que le permite moverse eficientemente<br \/>\npor la ciudad y alcanzar r\u00e1pidamente la velocidad necesaria.<br \/>\nEl patinete el\u00e9ctrico est\u00e1 equipado con una bater\u00eda de 15,6 Ah y 48 V,<br \/>\nque le permite recorrer hasta 60 km, dependiendo de la velocidad del veh\u00edculo.<br \/>\nEl modelo X-City Pro Max est\u00e1 fabricado en aluminio aeron\u00e1utico y<br \/>\ntiene un dise\u00f1o plegable. Esto facilita su transporte y almacenamiento en casa.<br \/>\nTodos los cables pasan por el interior del chasis,<br \/>\npara que no molesten durante la conducci\u00f3n.<br \/>\nSu distintiva combinaci\u00f3n de colores negro y naranja llama la atenci\u00f3n<br \/>\ny se adapta perfectamente al ajetreo de la vida urbana.<br \/>\nEl X-City Pro Max cuenta con frenos de disco regenerativos fiables<br \/>\nque le ayudan a reducir la velocidad r\u00e1pidamente y a recuperar la energ\u00eda de la bater\u00eda.<br \/>\nSus tres modos de velocidad le permiten personalizar el ritmo para usted o su hijo.<br \/>\nUna plataforma con estructura de alivio que mantiene los pies firmemente en su lugar<\/span><\/h4>\n","protected":false},"featured_media":4609,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[28,114,32],"product_tag":[],"class_list":["post-4604","product","type-product","status-publish","has-post-thumbnail","product_cat-bicicletas","product_cat-monopatines","product_cat-productos","desktop-align-center","tablet-align-left","mobile-align-left","first","outofstock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Monopat\u00edn El\u00e9ctrico Proove XCity Pro Max 550W - Imperio Electrodom\u00e9sticos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/imperioelectrodomesticos.uy\/index.php\/producto\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monopat\u00edn El\u00e9ctrico Proove XCity Pro Max 550W - Imperio Electrodom\u00e9sticos\" \/>\n<meta property=\"og:description\" content=\"Scooter El\u00e9ctrico Proove XCity Pro Max 550W &nbsp;   Capacidad de la bater\u00eda: 15,6 Ah 48 V Montaje de la bater\u00eda: Extra\u00edble Tipo de bater\u00eda: Litio Potencia de carga: 2,0 A Subida en pendientes: hasta 25\u00b0 Peso del dispositivo: 23 kg Reposapi\u00e9s: Aluminio, punta de pl\u00e1stico duro Material del cuadro: Aluminio de aviaci\u00f3n Frenos delanteros: Disco + Regenerativo Luz delantera: Linterna LED Tiempo de carga completa: 7 horas Garant\u00eda: 6 meses Fijaci\u00f3n del manillar: No extra\u00edble Material del manillar: Poliuretano texturizado de dureza media M\u00e1x. Reserva de marcha: 60 km Carga m\u00e1xima: hasta 120 kg Velocidad m\u00e1xima: 40 km\/h Rueda motriz: Impermeable N\u00famero de modos de velocidad: 3 Potencia nominal: 550 W Frenos traseros: Disco + Regenerativo Luz trasera: Linterna LED Edad recomendada: a partir de 16 a\u00f1os Neum\u00e1ticos: Goma resistente al desgaste Tipo de neum\u00e1ticos: Sin c\u00e1mara Impermeable: IP54 Di\u00e1metro de las ruedas: 10&quot; El modelo X-City Pro Max tiene una potencia m\u00e1xima de 550 W y una velocidad m\u00e1xima de 40 km\/h, lo que le permite moverse eficientemente por la ciudad y alcanzar r\u00e1pidamente la velocidad necesaria. El patinete el\u00e9ctrico est\u00e1 equipado con una bater\u00eda de 15,6 Ah y 48 V, que le permite recorrer hasta 60 km, dependiendo de la velocidad del veh\u00edculo. El modelo X-City Pro Max est\u00e1 fabricado en aluminio aeron\u00e1utico y tiene un dise\u00f1o plegable. Esto facilita su transporte y almacenamiento en casa. Todos los cables pasan por el interior del chasis, para que no molesten durante la conducci\u00f3n. Su distintiva combinaci\u00f3n de colores negro y naranja llama la atenci\u00f3n y se adapta perfectamente al ajetreo de la vida urbana. El X-City Pro Max cuenta con frenos de disco regenerativos fiables que le ayudan a reducir la velocidad r\u00e1pidamente y a recuperar la energ\u00eda de la bater\u00eda. Sus tres modos de velocidad le permiten personalizar el ritmo para usted o su hijo. Una plataforma con estructura de alivio que mantiene los pies firmemente en su lugar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/imperioelectrodomesticos.uy\/index.php\/producto\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\/\" \/>\n<meta property=\"og:site_name\" content=\"Imperio Electrodom\u00e9sticos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/imperioelectrodomesticos\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T14:11:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/imperioelectrodomesticos.uy\/wp-content\/uploads\/2025\/07\/monopatin-550.1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/index.php\\\/producto\\\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\\\/\",\"url\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/index.php\\\/producto\\\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\\\/\",\"name\":\"Monopat\u00edn El\u00e9ctrico Proove XCity Pro Max 550W - Imperio Electrodom\u00e9sticos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/index.php\\\/producto\\\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/index.php\\\/producto\\\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/monopatin-550.1.webp\",\"datePublished\":\"2025-07-30T16:21:59+00:00\",\"dateModified\":\"2026-02-04T14:11:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/index.php\\\/producto\\\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/index.php\\\/producto\\\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/index.php\\\/producto\\\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\\\/#primaryimage\",\"url\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/monopatin-550.1.webp\",\"contentUrl\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/monopatin-550.1.webp\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/index.php\\\/producto\\\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/index.php\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Monopat\u00edn El\u00e9ctrico Proove XCity Pro Max 550W\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/#website\",\"url\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/\",\"name\":\"Imperio Electrodom\u00e9sticos\",\"description\":\"Todo en electrodom\u00e9sticos y art\u00edculos para el hogar\",\"publisher\":{\"@id\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/#organization\"},\"alternateName\":\"Imperio Electrodom\u00e9sticos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/#organization\",\"name\":\"Imperio Electrodom\u00e9sticos\",\"url\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-ELECTRODOMESTICOS-3.png\",\"contentUrl\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-ELECTRODOMESTICOS-3.png\",\"width\":1080,\"height\":245,\"caption\":\"Imperio Electrodom\u00e9sticos\"},\"image\":{\"@id\":\"https:\\\/\\\/imperioelectrodomesticos.uy\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/imperioelectrodomesticos\\\/\",\"https:\\\/\\\/www.instagram.com\\\/imperioelectrodomesticos.uy\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monopat\u00edn El\u00e9ctrico Proove XCity Pro Max 550W - Imperio Electrodom\u00e9sticos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/imperioelectrodomesticos.uy\/index.php\/producto\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\/","og_locale":"es_ES","og_type":"article","og_title":"Monopat\u00edn El\u00e9ctrico Proove XCity Pro Max 550W - Imperio Electrodom\u00e9sticos","og_description":"Scooter El\u00e9ctrico Proove XCity Pro Max 550W &nbsp;   Capacidad de la bater\u00eda: 15,6 Ah 48 V Montaje de la bater\u00eda: Extra\u00edble Tipo de bater\u00eda: Litio Potencia de carga: 2,0 A Subida en pendientes: hasta 25\u00b0 Peso del dispositivo: 23 kg Reposapi\u00e9s: Aluminio, punta de pl\u00e1stico duro Material del cuadro: Aluminio de aviaci\u00f3n Frenos delanteros: Disco + Regenerativo Luz delantera: Linterna LED Tiempo de carga completa: 7 horas Garant\u00eda: 6 meses Fijaci\u00f3n del manillar: No extra\u00edble Material del manillar: Poliuretano texturizado de dureza media M\u00e1x. Reserva de marcha: 60 km Carga m\u00e1xima: hasta 120 kg Velocidad m\u00e1xima: 40 km\/h Rueda motriz: Impermeable N\u00famero de modos de velocidad: 3 Potencia nominal: 550 W Frenos traseros: Disco + Regenerativo Luz trasera: Linterna LED Edad recomendada: a partir de 16 a\u00f1os Neum\u00e1ticos: Goma resistente al desgaste Tipo de neum\u00e1ticos: Sin c\u00e1mara Impermeable: IP54 Di\u00e1metro de las ruedas: 10\" El modelo X-City Pro Max tiene una potencia m\u00e1xima de 550 W y una velocidad m\u00e1xima de 40 km\/h, lo que le permite moverse eficientemente por la ciudad y alcanzar r\u00e1pidamente la velocidad necesaria. El patinete el\u00e9ctrico est\u00e1 equipado con una bater\u00eda de 15,6 Ah y 48 V, que le permite recorrer hasta 60 km, dependiendo de la velocidad del veh\u00edculo. El modelo X-City Pro Max est\u00e1 fabricado en aluminio aeron\u00e1utico y tiene un dise\u00f1o plegable. Esto facilita su transporte y almacenamiento en casa. Todos los cables pasan por el interior del chasis, para que no molesten durante la conducci\u00f3n. Su distintiva combinaci\u00f3n de colores negro y naranja llama la atenci\u00f3n y se adapta perfectamente al ajetreo de la vida urbana. El X-City Pro Max cuenta con frenos de disco regenerativos fiables que le ayudan a reducir la velocidad r\u00e1pidamente y a recuperar la energ\u00eda de la bater\u00eda. Sus tres modos de velocidad le permiten personalizar el ritmo para usted o su hijo. Una plataforma con estructura de alivio que mantiene los pies firmemente en su lugar","og_url":"https:\/\/imperioelectrodomesticos.uy\/index.php\/producto\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\/","og_site_name":"Imperio Electrodom\u00e9sticos","article_publisher":"https:\/\/www.facebook.com\/imperioelectrodomesticos\/","article_modified_time":"2026-02-04T14:11:40+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/imperioelectrodomesticos.uy\/wp-content\/uploads\/2025\/07\/monopatin-550.1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/imperioelectrodomesticos.uy\/index.php\/producto\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\/","url":"https:\/\/imperioelectrodomesticos.uy\/index.php\/producto\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\/","name":"Monopat\u00edn El\u00e9ctrico Proove XCity Pro Max 550W - Imperio Electrodom\u00e9sticos","isPartOf":{"@id":"https:\/\/imperioelectrodomesticos.uy\/#website"},"primaryImageOfPage":{"@id":"https:\/\/imperioelectrodomesticos.uy\/index.php\/producto\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\/#primaryimage"},"image":{"@id":"https:\/\/imperioelectrodomesticos.uy\/index.php\/producto\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\/#primaryimage"},"thumbnailUrl":"https:\/\/imperioelectrodomesticos.uy\/wp-content\/uploads\/2025\/07\/monopatin-550.1.webp","datePublished":"2025-07-30T16:21:59+00:00","dateModified":"2026-02-04T14:11:40+00:00","breadcrumb":{"@id":"https:\/\/imperioelectrodomesticos.uy\/index.php\/producto\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/imperioelectrodomesticos.uy\/index.php\/producto\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/imperioelectrodomesticos.uy\/index.php\/producto\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\/#primaryimage","url":"https:\/\/imperioelectrodomesticos.uy\/wp-content\/uploads\/2025\/07\/monopatin-550.1.webp","contentUrl":"https:\/\/imperioelectrodomesticos.uy\/wp-content\/uploads\/2025\/07\/monopatin-550.1.webp","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/imperioelectrodomesticos.uy\/index.php\/producto\/monopatin-scooter-electrico-proove-xcity-pro-max-550w\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/imperioelectrodomesticos.uy\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/imperioelectrodomesticos.uy\/index.php\/tienda\/"},{"@type":"ListItem","position":3,"name":"Monopat\u00edn El\u00e9ctrico Proove XCity Pro Max 550W"}]},{"@type":"WebSite","@id":"https:\/\/imperioelectrodomesticos.uy\/#website","url":"https:\/\/imperioelectrodomesticos.uy\/","name":"Imperio Electrodom\u00e9sticos","description":"Todo en electrodom\u00e9sticos y art\u00edculos para el hogar","publisher":{"@id":"https:\/\/imperioelectrodomesticos.uy\/#organization"},"alternateName":"Imperio Electrodom\u00e9sticos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/imperioelectrodomesticos.uy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/imperioelectrodomesticos.uy\/#organization","name":"Imperio Electrodom\u00e9sticos","url":"https:\/\/imperioelectrodomesticos.uy\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/imperioelectrodomesticos.uy\/#\/schema\/logo\/image\/","url":"https:\/\/imperioelectrodomesticos.uy\/wp-content\/uploads\/2025\/03\/cropped-ELECTRODOMESTICOS-3.png","contentUrl":"https:\/\/imperioelectrodomesticos.uy\/wp-content\/uploads\/2025\/03\/cropped-ELECTRODOMESTICOS-3.png","width":1080,"height":245,"caption":"Imperio Electrodom\u00e9sticos"},"image":{"@id":"https:\/\/imperioelectrodomesticos.uy\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/imperioelectrodomesticos\/","https:\/\/www.instagram.com\/imperioelectrodomesticos.uy\/"]}]}},"_links":{"self":[{"href":"https:\/\/imperioelectrodomesticos.uy\/index.php\/wp-json\/wp\/v2\/product\/4604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imperioelectrodomesticos.uy\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/imperioelectrodomesticos.uy\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imperioelectrodomesticos.uy\/index.php\/wp-json\/wp\/v2\/media\/4609"}],"wp:attachment":[{"href":"https:\/\/imperioelectrodomesticos.uy\/index.php\/wp-json\/wp\/v2\/media?parent=4604"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/imperioelectrodomesticos.uy\/index.php\/wp-json\/wp\/v2\/product_brand?post=4604"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/imperioelectrodomesticos.uy\/index.php\/wp-json\/wp\/v2\/product_cat?post=4604"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/imperioelectrodomesticos.uy\/index.php\/wp-json\/wp\/v2\/product_tag?post=4604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}